{"id":2414,"date":"2026-03-12T21:16:54","date_gmt":"2026-03-12T21:16:54","guid":{"rendered":"https:\/\/wve.png.mybluehost.me\/website_71bd5955\/fermer-les-yeux-pour-mieux-entendre\/"},"modified":"2026-03-20T14:33:36","modified_gmt":"2026-03-20T14:33:36","slug":"fermer-les-yeux-pour-mieux-entendre","status":"publish","type":"post","link":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/","title":{"rendered":"Fermer les yeux pour mieux entendre"},"content":{"rendered":"\n<div class=\"gb-element-47b7678c\">\n<p class=\"gb-text gb-text-d25d691c\"><a href=\"https:\/\/chriswatson.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">Chris Watson<\/a>, preneur de son, artiste sonore et musicien, m&#8217;a g\u00e9n\u00e9reusement prodigu\u00e9 de nombreux conseils lors d&#8217;un atelier technique auquel j&#8217;ai particip\u00e9 en Islande. Parmi eux, l&#8217;un m&#8217;a particuli\u00e8rement surpris.<\/p>\n\n\n\n<p class=\"gb-text gb-text-99744473\">Je lui avais indiqu\u00e9 qu&#8217;\u00e0 mon retour \u00e0 Montr\u00e9al, je me pr\u00e9parais \u00e0 concevoir une installation \u00e0 partir de ma composition\u00a0<em><a href=\"https:\/\/wermenlinger.com\/fr\/resonnance\/\" type=\"post\" id=\"789\">R\u00e9sonnance<\/a><\/em>, une pi\u00e8ce consacr\u00e9e au fleuve Saint-Laurent. Il me demanda comment je comptais m&#8217;y prendre. Je lui r\u00e9pondis que je disposais de belles photos, de quelques vid\u00e9os et, bien entendu, de ma composition. Il me regarda avec un l\u00e9ger sourire et me dit ceci :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Si tu pr\u00e9sentes des \u00e9l\u00e9ments visuels avec ta composition, tes invit\u00e9s viendront te voir \u00e0 la fin et te diront qu&#8217;ils ont beaucoup appr\u00e9ci\u00e9. Si, par contre, tu ne leur offres que la bande audio dans une atmosph\u00e8re \u00e0 la lumi\u00e8re tamis\u00e9e, ils te diront alors, avec enthousiasme, qu&#8217;ils viennent de vivre une exp\u00e9rience unique et vraiment enrichissante. <\/p>\n<\/blockquote>\n\n\n\n<p class=\"gb-text\">J&#8217;ai mis sa recommandation en pratique. Plusieurs amis et collaborateurs \u00e0 qui j&#8217;en avais parl\u00e9 \u00e9taient sceptiques, et j&#8217;admets avoir moi-m\u00eame \u00e9t\u00e9 nerveux lors de la premi\u00e8re pr\u00e9sentation. Pourtant, il avait raison : j&#8217;ai re\u00e7u de nombreux t\u00e9moignages allant dans ce sens.  <\/p>\n\n\n\n<p class=\"gb-text\">Bien entendu, cela ne s&#8217;applique pas \u00e0 toutes les situations, et l&#8217;utilisation du visuel, avec parcimonie, peut \u00e9galement enrichir l&#8217;exp\u00e9rience de l&#8217;auditeur. Tout est, je crois, une question de dosage. <\/p>\n\n\n\n<p class=\"gb-text\">L&#8217;essentiel est de faire appel \u00e0 l&#8217;imagination de l&#8217;auditeur, car c&#8217;est elle qui le rend v\u00e9ritablement actif dans son \u00e9coute; non pas spectateur passif, mais co-cr\u00e9ateur de l&#8217;exp\u00e9rience.<\/p>\n\n\n\n<p class=\"gb-text\">Qui n&#8217;a jamais \u00e9t\u00e9 seul dans le noir en for\u00eat, ne serait-ce que quelques minutes, pour r\u00e9aliser \u00e0 quel point l&#8217;imagination peut \u00eatre puissante ?<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Que se passe-t-il lorsque nous cessons de regarder pour enfin \u00e9couter r\u00e9ellement? \u00c0 la suite d&#8217;un mentorat avec Chris Watson en Islande, j&#8217;ai explor\u00e9 le pouvoir de pr\u00e9senter le son dans la p\u00e9nombre pour faire de l&#8217;imaginaire de l&#8217;auditeur un co-cr\u00e9ateur de l&#8217;exp\u00e9rience. En privil\u00e9giant la \u00ab vibration physique d&#8217;un lieu \u00bb plut\u00f4t que la photographie, on invite un engagement plus puissant et personnel avec l&#8217;environnement sonore.  <\/p>\n","protected":false},"author":2,"featured_media":1909,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[26],"tags":[],"class_list":["post-2414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blogue"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fermer les yeux pour mieux entendre | Laurent Wermenlinger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fermer les yeux pour mieux entendre | Laurent Wermenlinger\" \/>\n<meta property=\"og:description\" content=\"Que se passe-t-il lorsque nous cessons de regarder pour enfin \u00e9couter r\u00e9ellement? \u00c0 la suite d&#039;un mentorat avec Chris Watson en Islande, j&#039;ai explor\u00e9 le pouvoir de pr\u00e9senter le son dans la p\u00e9nombre pour faire de l&#039;imaginaire de l&#039;auditeur un co-cr\u00e9ateur de l&#039;exp\u00e9rience. En privil\u00e9giant la \u00ab vibration physique d&#039;un lieu \u00bb plut\u00f4t que la photographie, on invite un engagement plus puissant et personnel avec l&#039;environnement sonore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/\" \/>\n<meta property=\"og:site_name\" content=\"Laurent Wermenlinger\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T21:16:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-20T14:33:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marieclaude\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"marieclaude\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/\"},\"author\":{\"name\":\"marieclaude\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c0def04c9805c74d26fdc5d5de92a2f\"},\"headline\":\"Fermer les yeux pour mieux entendre\",\"datePublished\":\"2026-03-12T21:16:54+00:00\",\"dateModified\":\"2026-03-20T14:33:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#\\\/schema\\\/person\\\/a47dbc1b0000ebf01029107ca89a5feb\"},\"image\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/laurent-2.jpg\",\"articleSection\":[\"Blogue\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/\",\"url\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/\",\"name\":\"Fermer les yeux pour mieux entendre | Laurent Wermenlinger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/laurent-2.jpg\",\"datePublished\":\"2026-03-12T21:16:54+00:00\",\"dateModified\":\"2026-03-20T14:33:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/laurent-2.jpg\",\"contentUrl\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/laurent-2.jpg\",\"width\":2500,\"height\":1667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/fermer-les-yeux-pour-mieux-entendre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fermer les yeux pour mieux entendre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/\",\"name\":\"Laurent Wermenlinger\",\"description\":\"Capturing the Breath of the Natural World\",\"publisher\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#\\\/schema\\\/person\\\/a47dbc1b0000ebf01029107ca89a5feb\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#\\\/schema\\\/person\\\/a47dbc1b0000ebf01029107ca89a5feb\",\"name\":\"WERMENLINGERL2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-Laurent-Wermenlinger.svg\",\"url\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-Laurent-Wermenlinger.svg\",\"contentUrl\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-Laurent-Wermenlinger.svg\",\"width\":579,\"height\":53,\"caption\":\"WERMENLINGERL2\"},\"logo\":{\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/logo-Laurent-Wermenlinger.svg\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c0def04c9805c74d26fdc5d5de92a2f\",\"name\":\"marieclaude\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g\",\"caption\":\"marieclaude\"},\"url\":\"https:\\\/\\\/wermenlinger.com\\\/fr\\\/author\\\/marieclaude\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fermer les yeux pour mieux entendre | Laurent Wermenlinger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/","og_locale":"fr_FR","og_type":"article","og_title":"Fermer les yeux pour mieux entendre | Laurent Wermenlinger","og_description":"Que se passe-t-il lorsque nous cessons de regarder pour enfin \u00e9couter r\u00e9ellement? \u00c0 la suite d'un mentorat avec Chris Watson en Islande, j'ai explor\u00e9 le pouvoir de pr\u00e9senter le son dans la p\u00e9nombre pour faire de l'imaginaire de l'auditeur un co-cr\u00e9ateur de l'exp\u00e9rience. En privil\u00e9giant la \u00ab vibration physique d'un lieu \u00bb plut\u00f4t que la photographie, on invite un engagement plus puissant et personnel avec l'environnement sonore.","og_url":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/","og_site_name":"Laurent Wermenlinger","article_published_time":"2026-03-12T21:16:54+00:00","article_modified_time":"2026-03-20T14:33:36+00:00","og_image":[{"width":2500,"height":1667,"url":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg","type":"image\/jpeg"}],"author":"marieclaude","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"marieclaude","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#article","isPartOf":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/"},"author":{"name":"marieclaude","@id":"https:\/\/wermenlinger.com\/fr\/#\/schema\/person\/2c0def04c9805c74d26fdc5d5de92a2f"},"headline":"Fermer les yeux pour mieux entendre","datePublished":"2026-03-12T21:16:54+00:00","dateModified":"2026-03-20T14:33:36+00:00","mainEntityOfPage":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/"},"wordCount":326,"publisher":{"@id":"https:\/\/wermenlinger.com\/fr\/#\/schema\/person\/a47dbc1b0000ebf01029107ca89a5feb"},"image":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#primaryimage"},"thumbnailUrl":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg","articleSection":["Blogue"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/","url":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/","name":"Fermer les yeux pour mieux entendre | Laurent Wermenlinger","isPartOf":{"@id":"https:\/\/wermenlinger.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#primaryimage"},"image":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#primaryimage"},"thumbnailUrl":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg","datePublished":"2026-03-12T21:16:54+00:00","dateModified":"2026-03-20T14:33:36+00:00","breadcrumb":{"@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#primaryimage","url":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg","contentUrl":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/laurent-2.jpg","width":2500,"height":1667},{"@type":"BreadcrumbList","@id":"https:\/\/wermenlinger.com\/fr\/fermer-les-yeux-pour-mieux-entendre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wermenlinger.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Fermer les yeux pour mieux entendre"}]},{"@type":"WebSite","@id":"https:\/\/wermenlinger.com\/fr\/#website","url":"https:\/\/wermenlinger.com\/fr\/","name":"Laurent Wermenlinger","description":"Capturing the Breath of the Natural World","publisher":{"@id":"https:\/\/wermenlinger.com\/fr\/#\/schema\/person\/a47dbc1b0000ebf01029107ca89a5feb"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wermenlinger.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/wermenlinger.com\/fr\/#\/schema\/person\/a47dbc1b0000ebf01029107ca89a5feb","name":"WERMENLINGERL2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/logo-Laurent-Wermenlinger.svg","url":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/logo-Laurent-Wermenlinger.svg","contentUrl":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/logo-Laurent-Wermenlinger.svg","width":579,"height":53,"caption":"WERMENLINGERL2"},"logo":{"@id":"https:\/\/wermenlinger.com\/wp-content\/uploads\/2026\/02\/logo-Laurent-Wermenlinger.svg"}},{"@type":"Person","@id":"https:\/\/wermenlinger.com\/fr\/#\/schema\/person\/2c0def04c9805c74d26fdc5d5de92a2f","name":"marieclaude","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f24822acad1319eceb35674011f50983536a61c45f0a8e8ab8ededce0136e150?s=96&d=mm&r=g","caption":"marieclaude"},"url":"https:\/\/wermenlinger.com\/fr\/author\/marieclaude\/"}]}},"_links":{"self":[{"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/posts\/2414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/comments?post=2414"}],"version-history":[{"count":4,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/posts\/2414\/revisions"}],"predecessor-version":[{"id":2466,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/posts\/2414\/revisions\/2466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/media\/1909"}],"wp:attachment":[{"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/media?parent=2414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/categories?post=2414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wermenlinger.com\/fr\/wp-json\/wp\/v2\/tags?post=2414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}